{"id":252157,"date":"2021-06-25T07:33:00","date_gmt":"2021-06-25T04:33:00","guid":{"rendered":"https:\/\/inform.click\/die-10-gemeinsten-diktatoren-unserer-zeit\/"},"modified":"2021-06-25T07:36:00","modified_gmt":"2021-06-25T04:36:00","slug":"die-10-gemeinsten-diktatoren-unserer-zeit","status":"publish","type":"post","link":"https:\/\/inform.click\/de\/die-10-gemeinsten-diktatoren-unserer-zeit\/","title":{"rendered":"Die 10 gemeinsten Diktatoren unserer Zeit"},"content":{"rendered":"<p>\n  Gegenw\u00e4rtig wird Demokratie in vielen L\u00e4ndern der Welt praktiziert. Die Menschen k\u00f6nnen w\u00e4hlen, wer die Regierung f\u00fchren soll und wer ihre Vertreter im Parlament sein werden. Dies war jedoch in der Vergangenheit nicht immer der Fall, als die Subjekte einer diktatorischen Herrschaft unterworfen waren. Einige Nationen stehen derzeit noch unter Diktatoren und leiden unter diesen Tyrannen. Diktatur kann als eine Form der Regierungsf\u00fchrung definiert werden, bei der ein Land oder ein Staat von einer Person oder einer kleinen Gruppe von Menschen regiert wird, die absolute Macht \u00fcber ihre Untertanen aus\u00fcben. In diesem Artikel werden wir die Top 10 der gemeinsten Diktatoren untersuchen, die jemals gelebt haben. Beginnen wir mit dem Countdown.\n<\/p>\n<h3>\n  10 Robert Mugabe (Simbabwe)<br \/>\n<\/h3>\n<p>\n  Robert Mugabe (Simbabwe).\n<\/p>\n<p>\n  Robert Mugabe ist der derzeitige Pr\u00e4sident von Simbabwe und seit 1987 an der Macht. Dieser 92-j\u00e4hrige Tyrann war ein Freiheitsk\u00e4mpfer und ein Liebling des Volkes, bevor er an die Macht kam. Seine Bem\u00fchungen, die Kolonialisten zu bek\u00e4mpfen, brachten ihm Gunst unter den Simbabwern und er wurde zum Pr\u00e4sidenten gew\u00e4hlt, sobald der Krieg vorbei war. Anschlie\u00dfend setzte er Simbabwe als Einparteienstaat ein. Jeder, der sich seiner F\u00fchrung widersetzte, wurde durch Ermordung oder Einsch\u00fcchterung eliminiert. Aus Angst, dass Wei\u00dfe sich seiner Herrschaft widersetzen k\u00f6nnten, verfolgte er alle Wei\u00dfen im fruchtbaren Hochland und nahm sich das ganze Land. Er erlie\u00df auch Gesetze, die es Ausl\u00e4ndern untersagten, mehr als 50% der Anteile an einem Unternehmen in Simbabwe zu besitzen. Diese dummen Ma\u00dfnahmen wirkten sich negativ auf die Wirtschaft Simbabwes aus und die B\u00fcrger litten v\u00f6llig darunter.\n<\/p>\n<h3>\n  9 Fidel Castro (Kuba)<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/top-10-meanest-dictators\/meanest-dictators-fidel-castro\/\" target=\"_blank\" rel=\"noopener\"><\/a>\n<\/p>\n<p>\n  Fidel Castro (Kuba).\n<\/p>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/10-most-popular-socialist-leaders-around-the-world\/\" target=\"_blank\" rel=\"noopener\">Fidel Castro ist das ehemalige Staatsoberhaupt Kubas<\/a>, das von 1976 bis 2008 als Pr\u00e4sident fungierte, als er seinem Bruder Raul Castro die Macht \u00fcbergab. Er behandelte Kuba wie seinen pers\u00f6nlichen Hof, indem er sich alle verfassungsm\u00e4\u00dfigen Regierungsbefugnisse \u00fcbertrug. Indem Fidel Castro den Kubanern das Recht verweigert, die F\u00fchrer ihrer Wahl zu w\u00e4hlen, schafft er es in die Liste der 10 gemeinsten Diktatoren unserer Zeit. Seine Regierung war f\u00fcr unz\u00e4hlige F\u00e4lle von Menschenrechtsverletzungen und den Massenexodus von \u00fcber einer Million Kubanern w\u00e4hrend des kubanischen Exils verantwortlich. Seine Haltung zum Kommunismus verarmte Kuba und das war der Hauptgrund f\u00fcr den Massenexodus.\n<\/p>\n<h3>\n  8 Joseph Stalin (UdSSR)<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/top-10-meanest-dictators\/meanest-dictators-joseph-stalin\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72774-6098c0454c066.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  Joseph Stalin (UdSSR).\n<\/p>\n<p>\n  <a href=\"https:\/\/inform.click\/de\/10-bose-zeitgenossische-diktatoren-tot-oder-lebendig\/\" title=\"Joseph Stalin\">Joseph Stalin<\/a> war von Mitte der 1920er Jahre bis zu seinem Tod 1952 der F\u00fchrer der Sowjetunion. Unter seiner Herrschaft wurde der Sozialismus in der UdSSR praktiziert, und diejenigen, die sich dieser Art von Regierungsf\u00fchrung widersetzten, wurden oft ohne ordnungsgem\u00e4\u00dfen Prozess inhaftiert, verbannt oder get\u00f6tet. W\u00e4hrend des Zweiten Weltkriegs schloss er einen Nichtangriffspakt mit Nazideutschland, aber Hitlers Streitkr\u00e4fte hielten sich nicht an diesen Pakt und griffen die UdSSR an. Dies f\u00fchrte zum Tod von \u00fcber einer Million Russen und zur Vertreibung vieler weiterer Russen. Durch den Abschluss eines Paktes mit Hitler opferte er das Wohlergehen und das Leben der Russen. Dies bringt ihm einen Platz in den Top 10 der gemeinsten Diktatoren unserer Zeit ein.\n<\/p>\n<h3>\n  7 Idi Amin Dada (Uganda)<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/top-10-meanest-dictators\/meanest-dictators-idi-amin-dada\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72774-6098c0475a013.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  Idi Amin Dada (Uganda).\n<\/p>\n<p>\n  <a href=\"https:\/\/inform.click\/de\/top-10-der-grausamsten-herrscher-aller-zeiten-in-der-geschichte\/\" title=\"Idi Amin regierte Uganda\">Idi Amin regierte Uganda<\/a> von 1971 bis 1979 <a href=\"https:\/\/inform.click\/de\/top-10-der-grausamsten-herrscher-aller-zeiten-in-der-geschichte\/\" title=\"acht Jahre lang\">acht Jahre lang<\/a>. Seine Herrschaft war gepr\u00e4gt von massiven Menschenrechtsverletzungen, politischen Attentaten und au\u00dfergerichtlichen Morden. Jeder, der es wagte, sich seiner Herrschaft zu widersetzen, wurde gr\u00f6\u00dftenteils ohne ordnungsgem\u00e4\u00dfen Prozess hingerichtet. Er war so gierig, dass er sogar die Frauen anderer Leute nahm und sie zu seinen eigenen machte. Er war nicht nur b\u00f6se und b\u00f6sartig, sondern auch ein Kannibale. Er w\u00fcrde Fleischst\u00fccke von denen schneiden, die er get\u00f6tet hat, und dann roh essen.\n<\/p>\n<h3>\n  6 Benito Mussolini (Italien)<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/top-10-meanest-dictators\/meanest-dictators-benito-mussolini\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72774-6098c0492019c.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  Gemeinste Diktatoren &#8211; Benito Mussolini (Italien).\n<\/p>\n<p>\n  Er war der Herrscher Italiens w\u00e4hrend des Zweiten Weltkriegs. Er war ein extremer Sozialist und zeigte eine totalit\u00e4re Herrschaft \u00fcber Italiener, indem er Italien zu einem Einparteienstaat machte. Er regierte Italien mit eiserner Faust, aber leider folgten ihm die Italiener immer noch. Er arbeitete <a href=\"https:\/\/inform.click\/de\/10-superwaffen-die-von-nazis-wahrend-des-zweiten-weltkriegs-gebaut-wurden\/\" title=\"w\u00e4hrend des Zweiten Weltkriegs\">w\u00e4hrend des Zweiten Weltkriegs<\/a> mit <a href=\"https:\/\/inform.click\/de\/10-superwaffen-die-von-nazis-wahrend-des-zweiten-weltkriegs-gebaut-wurden\/\" title=\"Nazideutschland zusammen\">Nazideutschland zusammen<\/a> und wurde schlie\u00dflich 1945 get\u00f6tet.\n<\/p>\n<h3>\n  5 Bashar Al Assad (Syrien)<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/top-10-meanest-dictators\/meanest-dictators-bashar-al-assad\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72774-6098c04ae3eca.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  Bashar Al Assad (Syrien).\n<\/p>\n<p>\n  <a href=\"https:\/\/inform.click\/de\/dies-sind-die-10-bosesten-herrscher-der-geschichte\/\" title=\"Bashar al-Assad\">Bashar al-Assad<\/a> ist der amtierende Pr\u00e4sident Syriens, obwohl er im In- und Ausland aufgefordert wurde, zur\u00fcckzutreten. Indem er an der Macht festh\u00e4lt, ist er f\u00fcr die derzeitige Zivilkrise in Syrien verantwortlich. Sein Regime ist r\u00fccksichtslos und gnadenlos in seinen Bem\u00fchungen, an der Macht zu bleiben. Sie haben sogar darauf zur\u00fcckgegriffen, Kinder im Alter von 2 Jahren zu t\u00f6ten, um jeden zu erschrecken, der sich seiner Regierung widersetzt. Trotz all dieser Gr\u00e4ueltaten ist er einer der gemeinsten Diktatoren unserer Zeit.\n<\/p>\n<h3>\n  4 Saddam Hussein (Irak)<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/top-10-meanest-dictators\/meanest-dictators-saddam-hussein\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72774-6098c04d1509c.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  Saddam Hussein (Irak).\n<\/p>\n<p>\n  Saddam Hussein war so grausam, dass er als erster Herrscher Massenvernichtungswaffen (WMD) gegen seine eigenen B\u00fcrger in der kurdischen Region einsetzte. Er trat in drei Kriege in den Irak ein, die zu massiven Kausalit\u00e4ten f\u00fchrten. Au\u00dfergerichtliche Morde waren unter seinem Regime \u00fcblich und der B\u00fcrger bef\u00fcrchtete in diesen schwierigen Zeiten das Schlimmste.\n<\/p>\n<h3>\n  3 Muammar Gaddafi (Libyen)<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/top-10-meanest-dictators\/meanest-dictators-muammar-gaddafi\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72774-6098c04f26b28.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  Muammar Gaddafi (Libyen).\n<\/p>\n<p>\n  Er regierte Libyen \u00fcber 42 Jahre lang bis zu seinem Tod im Jahr 2011. W\u00e4hrend dieser Zeit nutzte er Libyens \u00d6lreichtum, um sich und seine nahe Familie zu bereichern. Er regierte eigensinnig, so wenige wagten es, sich seiner Herrschaft zu widersetzen. Friedliche Demonstranten wurden oft von seinen Milit\u00e4rbeamten get\u00f6tet. Dies dauerte bis 2011, als die arabische Revolution in vollem Gange war. Dies motivierte die Libyer, aus bewaffnetem Protest auf die Stra\u00dfe zu gehen, bis sie einen der gemeinsten Diktatoren unserer Zeit t\u00f6ten konnten.\n<\/p>\n<h3>\n  2 Kim Jong II (Nordkorea)<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/top-10-meanest-dictators\/meanest-dictators-kim-jong-ii\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72774-6098c050cc609.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  Kim Jong-II (Nordkorea).\n<\/p>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/top-10-worst-world-leaders\/\" target=\"_blank\" rel=\"noopener\">Kim Jong-II war ein moderner Diktator<\/a>. Er verhaftete jeden, der sich seiner Arbeiterpartei widersetzte. Er w\u00fcrde sie in Arbeitslager einsperren, wo er sie \u00fcberarbeiten und verhungern w\u00fcrde. Er forderte von seinen B\u00fcrgern v\u00f6llige Loyalit\u00e4t und forderte sogar, dass sie ihn als den Obersten F\u00fchrer Nordkoreas bezeichnen. Diejenigen, die dies vers\u00e4umten, wurden hingerichtet oder in die Arbeitslager geworfen. Er war so besessen von milit\u00e4rischen Kriegen, dass er alle Staatsfinanzen in das Milit\u00e4r stecken w\u00fcrde. Dies l\u00e4hmte andere Abteilungen wie das Gesundheitswesen und es waren die B\u00fcrger, die am meisten darunter litten.\n<\/p>\n<h3>\n  1 Adolf Hitler (Deutschland)<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/top-10-meanest-dictators\/meanest-dictators-adolf-hitler\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72774-6098c052ca463.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  Adolf Hitler (Deutschland).\n<\/p>\n<p>\n  Er war der <a href=\"https:\/\/inform.click\/de\/top-10-erstaunliche-fakten-uber-adolf-hitler\/\" title=\"F\u00fchrer des nationalsozialistischen Deutschlands\">F\u00fchrer des nationalsozialistischen Deutschlands<\/a>. Er war pers\u00f6nlich verantwortlich f\u00fcr die Hinrichtung von \u00fcber einer Million unschuldiger Menschen, haupts\u00e4chlich der Juden. Er hasste die Juden so sehr, dass der einzige Weg, diesen Hass zu stoppen, darin bestand, alle Juden zu t\u00f6ten. Er leitete den <a href=\"https:\/\/www.wonderslist.com\/10-deadliest-wars-in-human-history\/\" target=\"_blank\" rel=\"noopener\">Zweiten Weltkrieg ein,<\/a> als er 1939 in Polen einfiel. Seine Handlungen und sein r\u00fccksichtsloses Wesen machen ihn daher zum gemeinsten Diktator unserer Zeit.\n<\/p>\n<h3>\n  Top 10 der gemeinsten Diktatoren unserer Zeit<br \/>\n<\/h3>\n<ol>\n<li>1 Adolf Hitler.\n  <\/li>\n<li>Kim Jong-II\n  <\/li>\n<li>Muammar Gaddafi\n  <\/li>\n<li>Saddam Hussein\n  <\/li>\n<li>Bashar al-Assad\n  <\/li>\n<li>Benito Mussolini\n  <\/li>\n<li>Idi Amin Dada\n  <\/li>\n<li>Joseph stali\n  <\/li>\n<li>Fidel Castro\n  <\/li>\n<li>Robert Mugabe.\n  <\/li>\n<\/ol>\n<div id=\"PostUnique_PostSource\" style=\"padding-top: 50px\">\n  Aufnahmequelle: <a target=\"_blank\" rel=\"noopener nofollow\" href=\"https:\/\/www.wonderslist.com\/top-10-meanest-dictators\/\">wonderslist.com<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hier ist eine Liste der 10 gemeinsten Diktatoren, die je gelebt haben. Einige Nationen stehen derzeit noch unter Diktatoren und leiden unter diesen Tyrannen.<\/p>\n","protected":false},"author":1,"featured_media":87115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[354],"tags":[],"class_list":["post-252157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unterhaltung"],"_links":{"self":[{"href":"https:\/\/inform.click\/de\/wp-json\/wp\/v2\/posts\/252157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inform.click\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inform.click\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inform.click\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inform.click\/de\/wp-json\/wp\/v2\/comments?post=252157"}],"version-history":[{"count":0,"href":"https:\/\/inform.click\/de\/wp-json\/wp\/v2\/posts\/252157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inform.click\/de\/wp-json\/wp\/v2\/media\/87115"}],"wp:attachment":[{"href":"https:\/\/inform.click\/de\/wp-json\/wp\/v2\/media?parent=252157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inform.click\/de\/wp-json\/wp\/v2\/categories?post=252157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inform.click\/de\/wp-json\/wp\/v2\/tags?post=252157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}