{"id":245488,"date":"2021-10-10T10:26:00","date_gmt":"2021-10-10T07:26:00","guid":{"rendered":"https:\/\/inform.click\/10-460\/"},"modified":"2021-10-10T10:29:00","modified_gmt":"2021-10-10T07:29:00","slug":"10-460","status":"publish","type":"post","link":"https:\/\/inform.click\/bn\/10-460\/","title":{"rendered":"\u09b6\u09c0\u09b0\u09cd\u09b7\u09b8\u09cd\u09a5\u09be\u09a8\u09c0\u09af\u09bc 10 \u099f\u09bf \u0996\u09be\u09ac\u09be\u09b0 \u09ac\u09be\u0995\u09c0 \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09b8\u09be\u09a5\u09c7 \u09aa\u09cd\u09b0\u09b8\u09cd\u09a4\u09c1\u09a4"},"content":{"rendered":"<p>\n  \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u098f\u0995\u099f\u09bf \u0985\u09a8\u09cd\u09a4\u09b0\u09cd\u09a8\u09bf\u09b9\u09bf\u09a4 \u09aa\u09cd\u09b0\u09a4\u09bf\u09ad\u09be \u09af\u09be \u09b8\u09ae\u09b8\u09cd\u09a4 \u09ae\u09be\u09a8\u09c1\u09b7\u09c7\u09b0 \u0985\u09a7\u09bf\u0995\u09be\u09b0\u09c0 possess \u09ac\u09c7\u0981\u099a\u09c7 \u09a5\u09be\u0995\u09be\u09b0 \u09aa\u09cd\u09b0\u09af\u09bc\u09cb\u099c\u09a8\u09c0\u09af\u09bc\u09a4\u09be \u09b6\u09bf\u0995\u09be\u09b0 \u098f\u09ac\u0982 \u0996\u09be\u09a6\u09cd\u09af\u09c7\u09b0 \u09b8\u09a8\u09cd\u09a7\u09be\u09a8 \u098f\u09ac\u0982 \u09ab\u09b2\u09b8\u09cd\u09ac\u09b0\u09c2\u09aa \u09b0\u09be\u09a8\u09cd\u09a8\u09be\u09b0 \u09aa\u09cd\u09b0\u09af\u09bc\u09cb\u099c\u09a8\u09c0\u09af\u09bc\u09a4\u09be\u09b0 \u099c\u09a8\u09cd\u09ae \u09a6\u09c7\u09af\u09bc\u0964 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u098f\u0995\u099f\u09bf \u09ac\u09bf\u099c\u09cd\u099e\u09be\u09a8 \u098f\u09ac\u0982 \u098f\u0995\u099f\u09bf \u09b6\u09bf\u09b2\u09cd\u09aa \u0989\u09ad\u09af\u09bc; \u09a4\u09be\u09b0 \u099c\u099f\u09bf\u09b2\u09a4\u09be \u098f\u09ac\u0982 \u09b8\u09a0\u09bf\u0995 \u0985\u09a8\u09c1\u09aa\u09be\u09a4\u09c7 \u09b8\u09a0\u09bf\u0995 \u0989\u09aa\u09be\u09a6\u09be\u09a8\u0997\u09c1\u09b2\u09bf\u09b0 \u09b8\u0982\u09ae\u09bf\u09b6\u09cd\u09b0\u09a3\u09c7\u09b0 \u099c\u09a8\u09cd\u09af \u09ac\u09bf\u099c\u09cd\u099e\u09be\u09a8 \u098f\u09ac\u0982 \u098f\u0995\u099f\u09bf \u09b8\u09cd\u09ac\u099c\u09cd\u099e\u09be\u09a4 \u098f\u09ac\u0982 \u09b8\u09c3\u099c\u09a8\u09b6\u09c0\u09b2 \u09b8\u09be\u09a7\u09a8\u09be \u09b9\u0993\u09af\u09bc\u09be\u09b0 \u099c\u09a8\u09cd\u09af \u098f\u0995\u099f\u09bf \u09b6\u09bf\u09b2\u09cd\u09aa\u0964 \u09af\u09a6\u09bf\u0993 \u0995\u09bf\u099b\u09c1 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u09b9'\u09b2 \u098f\u0995\u099f\u09bf \u09b8\u09cd\u09ac\u09b2\u09cd\u09aa \u09aa\u09cd\u09b0\u09b6\u0982\u09b8\u09bf\u09a4 \u09aa\u09cd\u09b0\u09a4\u09bf\u09a6\u09bf\u09a8\u09c7\u09b0 \u0995\u09cd\u09b0\u09bf\u09af\u09bc\u09be\u0995\u09b2\u09be\u09aa, \u0985\u09a8\u09cd\u09af\u09c7\u09b0 \u0995\u09be\u099b\u09c7 \u098f\u099f\u09bf\u09b0 \u0986\u09b6\u09c7\u09aa\u09be\u09b6\u09c7 \u09a8\u09bf\u0996\u09c1\u0981\u09a4 \u09aa\u09c7\u09b6\u09be \u09b0\u09af\u09bc\u09c7\u099b\u09c7\u0964\n<\/p>\n<p>\n  \u09b0\u09a8\u09cd\u09a7\u09a8\u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c0\u09af\u09bc \u09ac\u09bf\u09b6\u09c7\u09b7\u099c\u09cd\u099e\u09a6\u09c7\u09b0 \u099c\u09a8\u09cd\u09af \u098f\u099f\u09bf \u09b8\u09a0\u09bf\u0995 \u09b8\u09cd\u09ac\u09be\u09a6 \u098f\u09ac\u0982 \u09b8\u09a0\u09bf\u0995 \u0989\u09aa\u09be\u09a6\u09be\u09a8\u0997\u09c1\u09b2\u09bf \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7 \u09b9\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7 \u09a4\u09ac\u09c7 \u0995\u09cb\u09a8\u0993 \u09ac\u09be\u09a1\u09bc\u09bf\u09b0 \u099c\u09a8\u09cd\u09af \u09b8\u09a0\u09bf\u0995 \u09ae\u09cd\u09af\u09be\u099a \u098f\u09ac\u0982 \u0989\u09aa\u09be\u09a6\u09be\u09a8\u0997\u09c1\u09b2\u09bf\u09b0 \u0989\u09aa\u09b2\u09ad\u09cd\u09af\u09a4\u09be \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7 \u098f\u099f\u09bf \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u09b9\u09af\u09bc\u0964 \u09aa\u09cd\u09b0\u09b8\u09cd\u09a4\u09c1\u09a4 \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09b8\u09a0\u09bf\u0995 \u09aa\u09b0\u09bf\u09ae\u09be\u09a3\u099f\u09bf \u09a8\u09bf\u099c\u09c7\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u098f\u0995\u099f\u09bf \u099c\u099f\u09bf\u09b2 \u0985\u09cd\u09af\u09be\u09b2\u0997\u09b0\u09bf\u09a6\u09ae \u09af\u09be \u09aa\u09cd\u09b0\u09be\u09af\u09bc\u09b6\u0987 \u09ac\u09be\u09a1\u09bc\u09bf\u09a4\u09c7 \u09a1\u09bf\u09a8\u09be\u09b0 \u09ac\u09be \u09ae\u09a7\u09cd\u09af\u09be\u09b9\u09cd\u09a8\u09ad\u09cb\u099c \u09a5\u09c7\u0995\u09c7 \u09ac\u09be\u09ae \u0993\u09ad\u09be\u09b0\u09c7\u09b0 \u09a6\u09bf\u0995\u09c7 \u09a8\u09bf\u09af\u09bc\u09c7 \u09af\u09be\u09af\u09bc\u0964 \u09ac\u09be\u09ae\u09aa\u09be\u09b6\u09c7\u09b0 \u09a6\u09c2\u09b0\u09c7 \u09ab\u09c7\u09b2\u09c7 \u09a6\u09c7\u0993\u09af\u09bc\u09be \u098f\u0995\u099f\u09bf \u09ae\u09be\u09a8\u09b8\u09bf\u0995 \u098f\u09ac\u0982 \u0985\u09b0\u09cd\u09a5\u09a8\u09c8\u09a4\u09bf\u0995 \u0985\u09aa\u099a\u09af\u09bc \u09b9'\u09b2 \u09a4\u09be\u0987 \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09a7\u09be\u09b0\u09a3\u09be\u099f\u09bf \u0986\u09b8\u09c7 \u09af\u09be \u0987\u09a4\u09bf\u09ae\u09a7\u09cd\u09af\u09c7 \u09aa\u09cd\u09b0\u09b8\u09cd\u09a4\u09c1\u09a4 \u0996\u09be\u09ac\u09be\u09b0\u0995\u09c7 \u09b8\u09cd\u09ac\u09be\u09a6 \u098f\u09ac\u0982 \u099c\u09ae\u09bf\u09a8\u09c7\u09b0 \u099c\u09a8\u09cd\u09af \u09a4\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09a7\u09be\u09a8 \u0989\u09aa\u09be\u09a6\u09be\u09a8 \u09b9\u09bf\u09b8\u09be\u09ac\u09c7 \u09ac\u09cd\u09af\u09ac\u09b9\u09be\u09b0 \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u0964\n<\/p>\n<p>\n  \u0986\u09ae\u09b0\u09be \u098f\u09ae\u09a8 \u09a6\u09b6\u099f\u09bf \u09a6\u09cd\u09b0\u09c1\u09a4 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0997\u09a3\u09a8\u09be \u0995\u09b0\u09c7\u099b\u09bf \u09af\u09be \u0986\u09aa\u09a8\u09bf \u0998\u09b0\u09c7 \u09ac\u09be\u09ae \u0993\u09ad\u09be\u09b0 \u09ac\u09cd\u09af\u09ac\u09b9\u09be\u09b0 \u0995\u09b0\u09c7 \u09aa\u09cd\u09b0\u09b8\u09cd\u09a4\u09c1\u09a4 \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964 \u09b8\u09b9\u099c \u098f\u09ac\u0982 \u09a6\u09cd\u09b0\u09c1\u09a4 \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09a4\u09c7, \u0986\u09aa\u09a8\u09bf \u09a6\u09bf\u09a8\u09c7\u09b0 \u09af\u09c7 \u0995\u09cb\u09a8\u0993 \u09b8\u09ae\u09af\u09bc \u098f\u0997\u09c1\u09b2\u09bf \u0989\u09aa\u09ad\u09cb\u0997 \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964 \u098f\u0996\u09be\u09a8\u09c7 \u0985\u09ac\u09b6\u09bf\u09b7\u09cd\u099f \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u099c\u09a8\u09cd\u09af \u09aa\u09cd\u09b0\u09b8\u09cd\u09a4\u09c1\u09a4 10 \u099f\u09bf \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09a4\u09be\u09b2\u09bf\u0995\u09be \u09b0\u09af\u09bc\u09c7\u099b\u09c7\u0964\n<\/p>\n<h3>\n  1 \u09ae\u09be\u09b8\u0986\u09b2\u09be \u09ad\u09be\u09a4<br \/>\n<\/h3>\n<p>\n  \u09ae\u09be\u09b8\u09be\u09b2\u09be \u09ad\u09be\u09a4: \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09b8\u09be\u09a5\u09c7 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u0996\u09be\u09ac\u09be\u09b0\u0964\n<\/p>\n<p>\n  \u0986\u09aa\u09a8\u09bf \u09af\u09a6\u09bf \u09b0\u09be\u09a4\u09c7\u09b0 \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u099c\u09a8\u09cd\u09af \u09ae\u09bf\u09b6\u09cd\u09b0 \u09b6\u09be\u0995\u09b8\u09ac\u09cd\u099c\u09bf \u09ac\u09be \u09a4\u09b0\u0995\u09be\u09b0\u09bf \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09c7\u09a8 \u098f\u09ac\u0982 \u09b8\u09c7\u0997\u09c1\u09b2\u09bf \u098f\u0996\u09a8\u0993 \u09ab\u09cd\u09b0\u09bf\u099c\u09c7 \u09ac\u09b8\u09c7 \u09a5\u09be\u0995\u09c7 \u09a4\u09ac\u09c7 \u0986\u09aa\u09a8\u09bf \u098f\u099f\u09bf\u0995\u09c7 \u098f\u0995\u099f\u09bf \u09ae\u09be\u09b8\u09be\u09b2\u09be\u09b0 \u09ad\u09be\u099c\u09be \u09ad\u09be\u09a4\u09c7 \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964\n<\/p>\n<p>\n  \u0995\u09a1\u09bc\u09be\u0987\u09a4\u09c7 \u0995\u09bf\u099b\u09c1\u099f\u09be \u09a4\u09c7\u09b2 \u09ac\u09be \u09ae\u09be\u0996\u09a8 \u0997\u09b0\u09ae \u0995\u09b0\u09c1\u09a8\u0964 \u09a4\u09b0\u0995\u09be\u09b0\u09c0 \u09ac\u09be \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u09b6\u09be\u0995\u09b8\u09ac\u099c\u09bf \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8\u0964 \u09a4\u09be\u09b0\u09aa\u09b0\u09c7 \u098f\u09a4\u09c7 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u099a\u09be\u09b2 \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u09a4\u09be\u09a1\u09bc\u09be\u09a4\u09be\u09a1\u09bc\u09bf \u099f\u09b8 \u09a6\u09bf\u09a8\u0964 \u0995\u09bf\u099b\u09c1\u099f\u09be \u09a8\u09c1\u09a8 \u098f\u09ac\u0982 \u0997\u09c1\u0981\u09a1\u09bc\u09cb \u09ae\u09b0\u09bf\u099a \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8\u0964 \u09a4\u09be\u099c\u09be \u09a7\u09a8\u09bf\u09af\u09bc\u09be \u09aa\u09be\u09a4\u09be \u09ac\u09be \u099b\u09cb\u09b2\u09be \u09aa\u09a8\u09bf\u09b0 \u09a6\u09bf\u09af\u09bc\u09c7 \u09b8\u09be\u099c\u09bf\u09af\u09bc\u09c7 \u0997\u09b0\u09ae \u0997\u09b0\u09ae \u09aa\u09b0\u09bf\u09ac\u09c7\u09b6\u09a8 \u0995\u09b0\u09c1\u09a8\u0964\n<\/p>\n<h3>\n  2 \u09b0\u09cb\u099f\u09bf \u0989\u09aa\u09ae\u09be<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/10-dishes-prepared-with-leftover-food\/roti-upma-dish-prepared-with-leftover-food\/\" target=\"_blank\" rel=\"noopener\"><\/a>\n<\/p>\n<p>\n  \u09ac\u09be\u0995\u09c0 \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09b8\u09be\u09a5\u09c7 \u09a4\u09c8\u09b0\u09bf \u09b0\u09cb\u099f\u09bf \u0989\u09aa\u09ae\u09be \u09a1\u09bf\u09b6\u0964\n<\/p>\n<p>\n  \u09ac\u09be\u09ae \u0993\u09ad\u09be\u09b0 \u09b0\u09cb\u099f\u09bf\u09b8 \u098f\u0995\u099f\u09bf \u09ac\u09cd\u09af\u09a5\u09be \u098f\u09ac\u0982 \u09af\u0996\u09a8 \u0997\u09b0\u09ae \u0995\u09b0\u09be \u09b9\u09af\u09bc \u09a4\u09ac\u09c7 \u09af\u09be\u0987\u09b9\u09cb\u0995 \u09ad\u09be\u09b2 \u09b8\u09cd\u09ac\u09be\u09a6 \u09aa\u09be\u09ac\u09c7\u09a8 \u09a8\u09be\u0964 \u098f\u0997\u09c1\u09b2\u09bf \u09b8\u09b9\u099c\u09c7\u0987 \u09b0\u09cb\u099f\u09bf \u0989\u09aa\u09ae\u09be \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09be \u09af\u09be\u09af\u09bc\u0964\n<\/p>\n<p>\n  \u0986\u09aa\u09a8\u09be\u09b0 \u09af\u09be \u09a6\u09b0\u0995\u09be\u09b0 \u09a4\u09be \u09b9\u09b2 \u0995\u09bf\u099b\u09c1 \u09aa\u09c7\u0981\u09af\u09bc\u09be\u099c \u0995\u09be\u099f\u09be\u0964 \u098f\u0995\u099f\u09bf \u0995\u09a1\u09bc\u09be\u0987\u09a4\u09c7 \u09a4\u09c7\u09b2 \u0997\u09b0\u09ae \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u09b8\u09b0\u09bf\u09b7\u09be \u09ac\u09be\u099f\u09be \u09a6\u09bf\u09a8 \u09af\u09a4\u0995\u09cd\u09b7\u09a3 \u09a8\u09be \u09b8\u09c7\u0997\u09c1\u09b2\u09bf \u099b\u09a1\u09bc\u09bf\u09af\u09bc\u09c7 \u09aa\u09a1\u09bc\u09c7\u0964 \u0995\u09be\u099f\u09be \u09aa\u09c7\u0981\u09af\u09bc\u09be\u099c \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u09aa\u09cd\u09b0\u09be\u09af\u09bc \u098f\u0995 \u09ae\u09bf\u09a8\u09bf\u099f \u09a7\u09b0\u09c7 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09c1\u09a8\u0964 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u09b0\u09cb\u099f\u09bf\u09b8 \u099b\u09bf\u099f\u09bf\u09af\u09bc\u09c7 \u098f\u0997\u09c1\u09b2\u09bf\u0995\u09c7 \u0995\u09c7\u099f\u09c7 \u09a8\u09bf\u09a8 \u098f\u09ac\u0982 \u0995\u09a1\u09bc\u09be\u0987\u09a4\u09c7 \u09a4\u09b0\u0995\u09be\u09b0\u09bf \u09aa\u09be\u09a4\u09be \u098f\u09ac\u0982 \u09b8\u09ac\u09c1\u099c \u09ae\u09b0\u09bf\u099a \u09a6\u09bf\u09a8 \u098f\u09ac\u0982 \u09ae\u09bf\u09b6\u09bf\u09af\u09bc\u09c7 \u09a8\u09bf\u09a8\u0964 \u09b8\u09ac\u09c1\u099c \u09ae\u099f\u09b0, \u0995\u09be\u099f\u09be \u0997\u09be\u099c\u09b0, \u0995\u09bf\u099b\u09c1 \u09ae\u099f\u09b0\u09b6\u09c1\u099f\u09bf \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u09ad\u09be\u09b2\u09ad\u09be\u09ac\u09c7 \u09ae\u09c7\u09b6\u09be\u09a8\u0964 \u099f\u09c1\u0995\u09b0\u09cb \u099f\u09c1\u0995\u09b0\u09cb \u09b0\u09cb\u099f\u09bf\u09b8 \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u09ae\u09bf\u09b6\u09cd\u09b0\u09bf\u09a4 \u0995\u09b0\u09a4\u09c7 \u099f\u09b8 \u09a8\u09c1\u09a8, \u0985\u09b2\u09cd\u09aa \u099c\u09b2 \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u09ad\u09be\u09b2\u09ad\u09be\u09ac\u09c7 \u09ae\u09c7\u09b6\u09be\u09a8\u0964 \u099a\u09bf\u09a8\u09be\u09ac\u09be\u09a6\u09be\u09ae \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8, \u09ae\u09c7\u09b6\u09be\u09a4\u09c7 \u099f\u09b8 \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u098f\u0995 \u09ae\u09bf\u09a8\u09bf\u099f\u09c7\u09b0 \u099c\u09a8\u09cd\u09af \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09c1\u09a8\u0964 \u0995\u09bf\u099b\u09c1\u0995\u09cd\u09b7\u09a3 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09c1\u09a8\u0964 \u09ac\u09be\u09ae \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09b8\u09be\u09a5\u09c7 \u09aa\u09cd\u09b0\u09b8\u09cd\u09a4\u09c1\u09a4 \u0997\u09b0\u09ae \u098f\u0995\u099f\u09bf \u0986\u09b6\u09cd\u099a\u09b0\u09cd\u09af\u099c\u09a8\u0995 \u0996\u09be\u09ac\u09be\u09b0 \u09aa\u09b0\u09bf\u09ac\u09c7\u09b6\u09a8 \u0995\u09b0\u09c1\u09a8\u0964\n<\/p>\n<h3>\n  3 \u09b2\u099f \u099a\u09c1\u09b0\u09bf<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/10-dishes-prepared-with-leftover-food\/roti-churi-dish-prepared-with-leftover-food\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72837-6098c1f05afbd.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  \u09b0\u09cb\u099f\u09c0 \u099a\u09c1\u09b0\u09bf: \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09b8\u09be\u09a5\u09c7 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u0996\u09be\u09ac\u09be\u09b0\n<\/p>\n<p>\n  \u0986\u09b0 \u098f\u0995\u099f\u09bf \u09a7\u09be\u09b0\u09a3\u09be \u09af\u09c7\u0996\u09be\u09a8\u09c7 \u09ac\u09be\u0995\u09c0 \u09b0\u09cb\u099f\u09bf\u09b8\u0997\u09c1\u09b2\u09bf \u098f\u0995\u099f\u09bf \u09b8\u09c1\u09b8\u09cd\u09ac\u09be\u09a6\u09c1 \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u09aa\u09c1\u09a8\u09b0\u09be\u09af\u09bc \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09be \u09af\u09c7\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7 \u09a4\u09be \u09b9\u09b2\u09c7\u09a8 \u09b0\u09cb\u099f\u09bf \u099a\u09c1\u09b0\u09bf\u0964 \u0986\u09aa\u09a8\u09be\u09b0 \u09af\u09be \u09a6\u09b0\u0995\u09be\u09b0 \u09a4\u09be \u09b9'\u09b2 \u0995\u09af\u09bc\u09c7\u0995\u099f\u09bf \u099a\u09bf\u09a8\u09be\u09ac\u09be\u09a6\u09be\u09ae, \u0995\u09be\u099f\u09be \u09aa\u09c7\u0981\u09af\u09bc\u09be\u099c \u098f\u09ac\u0982 \u09b8\u09ac\u09c1\u099c \u09ae\u09b0\u09bf\u099a\u0964 \u0989\u09aa\u09be\u09a6\u09be\u09a8\u0997\u09c1\u09b2\u09bf \u0995\u09c7\u099f\u09c7 \u099f\u09c1\u0995\u09b0\u09cb \u099f\u09c1\u0995\u09b0\u09cb \u0995\u09b0\u09c7 \u09a8\u09bf\u09a8\u0964 \u0995\u09a1\u09bc\u09be\u0987\u09a4\u09c7 \u09a4\u09c7\u09b2 \u0997\u09b0\u09ae \u0995\u09b0\u09c7 \u09a4\u09be\u09a4\u09c7 \u099c\u09bf\u09b0\u09be \u09ac\u09be\u099f\u09be \u09a6\u09bf\u09a8 \u098f\u09ac\u0982 \u0995\u09bf\u099b\u09c1\u0995\u09cd\u09b7\u09a3 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09c1\u09a8\u0964 \u0995\u09bf\u099b\u09c1 \u0986\u09a6\u09be \u0995\u09c1\u099a\u09bf \u0995\u09b0\u09c7 \u0995\u09a1\u09bc\u09be\u0987\u09a4\u09c7 \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u0995\u09b7\u09be\u09a8 \u00e9 \u09b8\u09ac\u09c1\u099c \u09ae\u09b0\u09bf\u099a \u09aa\u09c7\u0981\u09af\u09bc\u09be\u099c \u098f\u09ac\u0982 \u099a\u09bf\u09a8\u09be\u09ac\u09be\u09a6\u09be\u09ae \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u09ad\u09be\u09b2\u09ad\u09be\u09ac\u09c7 \u09ae\u09c7\u09b6\u09be\u09a8\u0964 \u0985\u09ac\u09b6\u09bf\u09b7\u09cd\u099f \u099f\u09c1\u0995\u09b0\u09cb \u099f\u09c1\u0995\u09b0\u09cb \u099f\u09c1\u0995\u09b0\u09cb \u099f\u09c1\u0995\u09b0\u09cb \u099f\u09c1\u0995\u09b0\u09cb \u0995\u09b0\u09c7 \u09ab\u09c7\u09b2\u09c1\u09a8\u0964 \u09b9\u09b2\u09c1\u09a6 \u0997\u09c1\u0981\u09a1\u09bc\u09cb, \u09b2\u09ac\u09a3 \u098f\u09ac\u0982 \u099a\u09bf\u09a8\u09bf \u09a6\u09bf\u09a8 \u098f\u09ac\u0982 \u09ad\u09be\u09b2\u09ad\u09be\u09ac\u09c7 \u09ae\u09c7\u09b6\u09be\u09a8\u0964 \u0995\u09bf\u099b\u09c1\u0995\u09cd\u09b7\u09a3 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09c1\u09a8\u0964 \u09ac\u09be\u0995\u09c0 \u099f\u09c1\u0995\u09b0\u09cb \u099f\u09c1\u0995\u09b0\u09cb \u099f\u09c1\u0995\u09b0\u09cb \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u09b9\u09be\u09b2\u0995\u09be \u099f\u09b8 \u0995\u09b0\u09c1\u09a8\u0964 \u0986\u0981\u099a\u09c7 and\u09c7\u0995\u09c7 \u0986\u0981\u099a\u09c7 \u0985\u09b2\u09cd\u09aa \u0986\u0981\u099a\u09c7 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09c1\u09a8 \u09af\u09a4\u0995\u09cd\u09b7\u09a3 \u09a8\u09be \u09b0\u09cb\u099f\u09bf\u0997\u09c1\u09b2\u09bf \u0995\u09cd\u09b0\u099e\u09cd\u099a \u09b9\u09af\u09bc\u09c7 \u09af\u09be\u09af\u09bc\u0964 \u0997\u09b0\u09ae \u0997\u09b0\u09ae \u09aa\u09b0\u09bf\u09ac\u09c7\u09b6\u09a8 \u0995\u09b0\u09c1\u09a8\u0964\n<\/p>\n<h3>\n  4 \u09ad\u09be\u09a4 \u0995\u09be\u099a\u09be\u09b0\u09bf<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/10-dishes-prepared-with-leftover-food\/rice-kachri-dish-prepared-with-leftover-food\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72837-6098c1f26cde0.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  \u09ad\u09be\u09a4 \u0995\u09be\u099a\u09be\u09b0\u09bf: \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09b8\u09be\u09a5\u09c7 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u0996\u09be\u09ac\u09be\u09b0\u0964\n<\/p>\n<p>\n  \u09af\u09a6\u09bf \u09ad\u09be\u09a4\u09c7\u09b0 \u0995\u09bf\u099b\u09c1 \u09ac\u09be\u0995\u09c0 \u09a5\u09be\u0995\u09c7 \u09a4\u09ac\u09c7 \u0986\u09aa\u09a8\u09bf \u098f\u099f\u09bf\u0995\u09c7 \u09b8\u09b9\u099c\u09c7\u0987 \u0995\u09bf\u099b\u09c1 \u0995\u09bf\u099b\u09c1 \u099a\u0995\u099a\u0995\u09c7 \u09aa\u09b0\u09bf\u09a3\u09a4 \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964\n<\/p>\n<p>\n  \u098f\u0995\u099f\u09bf \u09aa\u09cd\u09af\u09be\u09a8 \u09a8\u09bf\u09a8\u0964 \u0995\u09bf\u099b\u09c1\u099f\u09be \u09a4\u09c7\u09b2 \u0997\u09b0\u09ae \u0995\u09b0\u09c7 \u09a8\u09be\u0987\u099c\u09c7\u09b2\u09be \u09ac\u09c0\u099c \u09ac\u09be \u0995\u09be\u09b2\u09cb\u09a8\u099c\u09bf \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8 rice \u09ac\u09be\u09ae \u09a6\u09bf\u0995\u09c7 \u0995\u09bf\u099b\u09c1\u099f\u09be \u099c\u09b2 \u09a7\u09be\u09a8\u09c7\u09b0 \u0989\u09aa\u09b0 \u099a\u09be\u09aa\u09c1\u09a8 \u098f\u09ac\u0982 \u09b8\u09c7\u09a6\u09cd\u09a7 \u09b9\u09a4\u09c7 \u09a6\u09bf\u09a8\u0964 \u09b8\u09be\u09ae\u09be\u09a8\u09cd\u09af \u09b2\u09ac\u09a3 \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u09ae\u09bf\u09b6\u09cd\u09b0\u09a3\u099f\u09bf \u0998\u09a8 \u09aa\u09c7\u09b8\u09cd\u099f \u09b9\u0993\u09af\u09bc\u09be \u09aa\u09b0\u09cd\u09af\u09a8\u09cd\u09a4 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09c1\u09a8\u0964 \u0995\u09bf\u099b\u09c1\u0995\u09cd\u09b7\u09a3 \u09a0\u09be\u09a8\u09cd\u09a1\u09be \u09b9\u09a4\u09c7 \u09a6\u09bf\u09a8\u0964<br \/>\n  \u098f\u0995\u099f\u09bf \u09aa\u09cd\u09b2\u09c7\u099f \u09a8\u09bf\u09a8 \u098f\u09ac\u0982 \u098f\u099f\u09bf \u0995\u09bf\u099b\u09c1 \u09a4\u09c7\u09b2 \u09a6\u09bf\u09af\u09bc\u09c7 \u0997\u09cd\u09b0\u09bf\u099c \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u09ae\u09bf\u09b6\u09cd\u09b0\u09a3\u099f\u09bf \u09aa\u099b\u09a8\u09cd\u09a6\u09b8\u0987 \u0986\u0995\u09be\u09b0\u09c7 .\u09be\u09b2\u09c1\u09a8\u0964 \u09b0\u09cb\u09a6\u09c7 \u09b6\u09c1\u0995\u09bf\u09af\u09bc\u09c7 \u09b0\u09be\u0996\u09c1\u09a8\u0964 \u098f\u0995\u09ac\u09be\u09b0 \u09b6\u09c1\u0995\u09a8\u09cb \u09b9\u09af\u09bc\u09c7 \u0997\u09c7\u09b2\u09c7, \u0986\u09aa\u09a8\u09bf \u0997\u09ad\u09c0\u09b0 \u09ad\u09be\u099c\u09be \u098f\u09ac\u0982 \u0995\u09cd\u09b0\u09bf\u09b8\u09cd\u09aa\u09bf\u099c\u0997\u09c1\u09b2\u09bf \u09b8\u09cd\u09ac\u09be\u09a6 \u09a8\u09bf\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964 \u098f\u099f\u09bf \u098f\u09af\u09bc\u09be\u09b0 \u099f\u09be\u0987\u099f \u09aa\u09be\u09a4\u09cd\u09b0\u09c7 \u09b8\u0982\u09b0\u0995\u09cd\u09b7\u09a3 \u0995\u09b0\u09be \u09af\u09c7\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7 \u098f\u09ac\u0982 \u09af\u0996\u09a8 \u0987\u099a\u09cd\u099b\u09be \u09b9\u09af\u09bc \u0996\u09be\u0993\u09af\u09bc\u09be \u09af\u09be\u09af\u09bc\u0964 \u098f\u099f\u09bf \u098f\u0995\u099f\u09bf \u09b8\u09b0\u09cd\u09ac\u0995\u09be\u09b2\u09c7\u09b0 \u09b8\u09cd\u09a8\u09cd\u09af\u09be\u0995\u09cd\u09b8 \u0996\u09be\u09ac\u09be\u09b0\u0997\u09c1\u09b2\u09bf \u09af\u09be \u09ac\u09be\u0995\u09c0 \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09b8\u09be\u09a5\u09c7 \u09aa\u09cd\u09b0\u09b8\u09cd\u09a4\u09c1\u09a4\u0964\n<\/p>\n<h3>\n  5 \u09a1\u09be\u09b2 \u09aa\u09be\u09a1\u09bc\u09be<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/10-dishes-prepared-with-leftover-food\/leftover-dal-paratha\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72837-6098c1f47516c.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  \u09ac\u09be\u09ae \u09a6\u09b2 \u09a1\u09be\u09b2 \u09aa\u09be\u09b0\u09cd\u09a5\u0964\n<\/p>\n<p>\n  \u09a1\u09be\u09b2 \u09aa\u09b0\u09cd\u09a5 \u09b9'\u09b2 \u0986\u09b0\u09c7\u0995\u099f\u09bf \u09a6\u09cd\u09b0\u09c1\u09a4 \u098f\u09ac\u0982 \u09b8\u09c1\u09b8\u09cd\u09ac\u09be\u09a6\u09c1 \u09b0\u09c7\u09b8\u09bf\u09aa\u09bf \u09af\u09be \u09a1\u09be\u09b2 \u09a6\u09bf\u09af\u09bc\u09c7 \u09ac\u09be\u09ae\u09c7 \u09a6\u09bf\u09af\u09bc\u09c7 \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09be \u09af\u09be\u09af\u09bc\u0964\n<\/p>\n<p>\n  \u099c\u09b2\u09c7\u09b0 \u09aa\u09b0\u09bf\u09ac\u09b0\u09cd\u09a4\u09c7 \u09a1\u09be\u09b2\u099f\u09bf \u09ae\u09af\u09bc\u09a6\u09be \u09ad\u09be\u0981\u099c\u09a4\u09c7 \u09ac\u09cd\u09af\u09ac\u09b9\u09be\u09b0 \u0995\u09b0\u09c1\u09a8\u0964 \u09a8\u09b0\u09ae \u0995\u09b0\u09be\u09b0 \u099c\u09a8\u09cd\u09af \u09ae\u09af\u09bc\u09a6\u09be\u09b0 \u09b8\u09ae\u09af\u09bc \u0995\u09bf\u099b\u09c1\u099f\u09be \u09a4\u09c7\u09b2 \u09a6\u09bf\u09a8 \u09a4\u09be\u09b0\u09aa\u09b0\u09c7 \u09af\u09a5\u09be\u09b0\u09c0\u09a4\u09bf \u09ae\u09af\u09bc\u09a6\u09be\u09b0 \u098f\u0995\u099f\u09bf \u099b\u09cb\u099f \u0985\u0982\u09b6 \u09a8\u09bf\u09a8\u0964 \u099b\u09cb\u099f \u099b\u09cb\u099f \u09ac\u09b2 \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u098f\u0997\u09c1\u09b2\u09bf \u098f\u0995\u099f\u09bf \u09b8\u09ae\u09a4\u09b2 \u09ac\u09c3\u09a4\u09cd\u09a4\u09be\u0995\u09be\u09b0 \u0986\u0995\u09be\u09b0\u09c7 \u09b0\u09cb\u09b2 \u0995\u09b0\u09c1\u09a8\u0964 \u098f\u099f\u09bf \u098f\u0995\u099f\u09bf \u09ab\u09cd\u09b2\u09cd\u09af\u09be\u099f \u09ab\u09cd\u09b0\u09be\u0987\u0982 \u09aa\u09cd\u09af\u09be\u09a8\u09c7 \u09b0\u09be\u0996\u09c1\u09a8\u0964 \u0995\u09bf\u099b\u09c1\u099f\u09be \u09a4\u09c7\u09b2 \u09ac\u09be \u0998\u09bf \u09a6\u09bf\u09a8 \u098f\u09ac\u0982 \u09a6\u09c1'\u09a6\u09bf\u0995\u09c7 \u09ac\u09be\u09a6\u09be\u09ae\u09bf \u09b9\u0993\u09af\u09bc\u09be \u09aa\u09b0\u09cd\u09af\u09a8\u09cd\u09a4 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09c1\u09a8\u0964\n<\/p>\n<h3>\n  6 \u09a4\u09c1\u09b0\u09b8\u09cd\u0995 \u098f\u09ac\u0982 \u099a\u09bf\u0995\u09c7\u09a8 \u09b8\u09cd\u09af\u09be\u09a8\u09cd\u09a1\u0989\u0987\u099a<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/10-dishes-prepared-with-leftover-food\/turkey-and-chicken-sandwich\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72837-6098c1f63b69d.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  \u09a4\u09c1\u09b0\u09b8\u09cd\u0995 \u098f\u09ac\u0982 \u099a\u09bf\u0995\u09c7\u09a8 \u09b8\u09cd\u09af\u09be\u09a8\u09cd\u09a1\u0989\u0987\u099a\u0964\n<\/p>\n<p>\n  \u0986\u09aa\u09a8\u09be\u09b0 \u09af\u09a6\u09bf \u0995\u09bf\u099b\u09c1 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u099f\u09be\u09b0\u09cd\u0995\u09bf \u09ac\u09be \u09ae\u09c1\u09b0\u0997\u09bf\u09b0 \u099f\u09bf\u0995\u09cd\u0995\u09be \u09ac\u09be \u09a4\u09a8\u09cd\u09a6\u09c1\u09b0\u09bf \u09a5\u09c7\u0995\u09c7 \u0995\u09bf\u099b\u09c1 \u09ae\u09c1\u09b0\u0997\u09bf \u09a5\u09be\u0995\u09c7 \u09a4\u09ac\u09c7 \u0986\u09aa\u09a8\u09bf \u098f\u099f\u09bf\u0995\u09c7 \u098f\u0995\u099f\u09bf \u09a6\u09c1\u09b0\u09cd\u09a6\u09be\u09a8\u09cd\u09a4 \u09b8\u09cd\u09af\u09be\u09a8\u09cd\u09a1\u0989\u0987\u099a \u09b9\u09bf\u09b8\u09be\u09ac\u09c7 \u09b0\u09c2\u09aa\u09be\u09a8\u09cd\u09a4\u09b0 \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964 \u09b0\u09c1\u099f\u09bf\u09b0 \u099f\u09c1\u0995\u09b0\u09cb \u09a8\u09bf\u09a8, \u098f\u099f\u09bf\u09a4\u09c7 \u0995\u09bf\u099b\u09c1 \u09ae\u09c7\u09af\u09bc\u09cb\u09a8\u09bf\u099c \u099b\u09a1\u09bc\u09bf\u09af\u09bc\u09c7 \u09a6\u09bf\u09a8\u0964 \u0995\u09bf\u099b\u09c1 \u099f\u09ae\u09c7\u099f\u09cb \u098f\u09ac\u0982 \u09b2\u09c7\u099f\u09c1\u09b8 \u09aa\u09be\u09a4\u09be \u0995\u09be\u099f\u09c1\u09a8\u0964 \u099b\u09bf\u09a8\u09cd\u09a8\u09be\u0982\u09b6 \u0985\u09ac\u09b6\u09c7\u09b7 \u09a4\u09c1\u09b0\u09b8\u09cd\u0995 \u09ac\u09be \u09ae\u09c1\u09b0\u0997\u09bf\u09b0 \u099f\u09c1\u0995\u09b0\u09be \u098f\u09ac\u0982 \u09a4\u09be\u09a6\u09c7\u09b0 \u09aa\u09c1\u09a8\u09b0\u09be\u09af\u09bc \u0997\u09b0\u09ae \u0995\u09b0\u09be \u0998\u09b0\u09c7\u09b0 \u09a4\u09be\u09aa\u09ae\u09be\u09a4\u09cd\u09b0\u09be\u0964 \u0995\u09be\u099f\u09be \u09ae\u09be\u0982\u09b8, \u099f\u09ae\u09c7\u099f\u09cb \u098f\u09ac\u0982 \u09b2\u09c7\u099f\u09c1\u09b8 \u09b0\u09c1\u099f\u09bf\u09b0 \u099f\u09c1\u0995\u09b0\u09cb\u09a4\u09c7 \u09b0\u09be\u0996\u09c1\u09a8\u0964 \u0986\u09aa\u09a8\u09bf \u098f\u099f\u09bf \u0997\u09cd\u09b0\u09bf\u09b2 \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8 \u09ac\u09be \u098f\u099f\u09bf \u09af\u09c7\u09ae\u09a8 \u0986\u099b\u09c7 \u09a4\u09c7\u09ae\u09a8 \u09a5\u09be\u0995\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964 \u099f\u09be\u09b0\u09cd\u0995\u09bf \u09ac\u09be \u09ae\u09c1\u09b0\u0997\u09bf\u09b0 \u09aa\u09b0\u09bf\u09ac\u09b0\u09cd\u09a4\u09c7, \u0986\u09aa\u09a8\u09bf \u09ac\u09be\u0995\u09c0 \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09b8\u09be\u09a5\u09c7 \u09a4\u09c8\u09b0\u09bf \u0986\u0999\u09c1\u09b2\u09c7\u09b0 \u09aa\u09be\u09a4\u09b2\u09be \u0996\u09be\u09ac\u09be\u09b0\u0997\u09c1\u09b2\u09bf \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09a4\u09c7 \u0996\u09c1\u09ac \u09ad\u09be\u09b2 \u09aa\u09a8\u09bf\u09b0 \u09ac\u09be \u09ae\u09be\u0982\u09b8\u09c7\u09b0 \u0993\u09aa\u09b0\u09c7 \u09ae\u09be\u0982\u09b8 \u09ac\u09cd\u09af\u09ac\u09b9\u09be\u09b0 \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964\n<\/p>\n<h3>\n  7 \u0987\u09a1\u09b2\u09bf \u09ae\u09be\u099e\u09cd\u099a\u09c1\u09b0\u09bf\u09af\u09bc\u09be\u09a8<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/10-dishes-prepared-with-leftover-food\/idli-manchurian\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72837-6098c1f80dad0.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  \u0987\u09a1\u09b2\u09bf \u09ae\u09be\u099e\u09cd\u099a\u09c1\u09b0\u09bf\u09af\u09bc\u09be\u09a8\u0964\n<\/p>\n<p>\n  \u0987\u09a1\u09b2\u09bf\u09b0 \u09ac\u09be\u09ae\u09a6\u09bf\u0995\u09c7, \u0986\u09aa\u09a8\u09bf \u098f\u099f\u09bf\u09b0 \u099c\u09a8\u09cd\u09af \u099a\u09be\u0987\u09a8\u09bf\u099c \u09b8\u09cd\u09aa\u09b0\u09cd\u09b6 \u09b8\u09b9 \u098f\u0995\u099f\u09bf \u09b8\u09ae\u09cd\u09aa\u09c2\u09b0\u09cd\u09a3 \u09a8\u09a4\u09c1\u09a8 \u09a5\u09be\u09b2\u09be \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964 \u0995\u09bf\u099b\u09c1 \u0995\u09b0\u09cd\u09a8\u09ab\u09cd\u09b2\u09be\u09b0, \u09b8\u09b0\u09c1 \u09ae\u09af\u09bc\u09a6\u09be, \u0986\u09a6\u09be \u09b0\u09b8\u09c1\u09a8\u09c7\u09b0 \u09aa\u09c7\u09b8\u09cd\u099f, \u09b2\u09be\u09b2 \u09ae\u09b0\u09bf\u099a \u0997\u09c1\u0981\u09a1\u09bc\u09cb \u098f\u09ac\u0982 \u099c\u09b2 \u09ae\u09bf\u09b6\u09bf\u09af\u09bc\u09c7 \u098f\u0995\u099f\u09bf \u09aa\u09c7\u09b8\u09cd\u099f \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09c1\u09a8\u0964\n<\/p>\n<p>\n  \u0987\u09a1\u09b2\u09bf\u09b8\u0995\u09c7 \u099b\u09cb\u099f \u099b\u09cb\u099f \u09b8\u09cd\u0995\u09cb\u09af\u09bc\u09be\u09b0\u09c7 \u0995\u09be\u099f\u09c1\u09a8, \u098f\u099f\u09bf\u0995\u09c7 \u09ac\u09be\u099f\u09be\u09a4\u09c7 \u09a1\u09c1\u09ac\u09bf\u09af\u09bc\u09c7 \u09ad\u09be\u099c\u09c1\u09a8\u0964 \u0985\u09a8\u09cd\u09af \u0995\u09a1\u09bc\u09be\u0987\u09a4\u09c7 \u0995\u09bf\u099b\u09c1\u099f\u09be \u09a4\u09c7\u09b2 \u0997\u09b0\u09ae \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u098f\u09a4\u09c7 \u09ac\u09b8\u09a8\u09cd\u09a4\u09c7\u09b0 \u09aa\u09c7\u0981\u09af\u09bc\u09be\u099c, \u0995\u09be\u099f\u09be \u09b0\u09b8\u09c1\u09a8 \u098f\u09ac\u0982 \u0986\u09a6\u09be \u09a6\u09bf\u09a8 \u098f\u09ac\u0982 \u098f\u0995\u099f\u09bf \u099f\u09b8 \u09a6\u09bf\u09a8\u0964 \u0995\u09cd\u09af\u09be\u09aa\u09b8\u09bf\u0995\u09be\u09ae \u098f\u09ac\u0982 \u09b8\u09af\u09bc\u09be \u09b8\u09b8 \u09af\u09c1\u0995\u09cd\u09a4 \u0995\u09b0\u09c7 \u0995\u09bf\u099b\u09c1\u0995\u09cd\u09b7\u09a3 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09c1\u09a8\u0964 \u099f\u09ae\u09c7\u099f\u09cb \u09b8\u09b8 \u098f\u09ac\u0982 \u09b2\u09ac\u09a3 \u098f\u09ac\u0982 \u09ae\u09b0\u09bf\u099a \u0997\u09c1\u0981\u09a1\u09bc\u09cb \u09b8\u09cd\u09ac\u09be\u09a6 \u0985\u09a8\u09c1\u09af\u09be\u09af\u09bc\u09c0 \u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8\u0964 \u09ae\u09bf\u09b6\u09cd\u09b0\u09a3\u099f\u09bf \u09b8\u09bf\u09a6\u09cd\u09a7 \u09b9\u09af\u09bc\u09c7 \u09a8\u09bf\u09a8\u0964 \u09a4\u09be\u09b0\u09aa\u09b0\u09c7 \u09ad\u09be\u099c\u09be \u0987\u09a1\u09b2\u09bf\u09b8 \u09af\u09cb\u0997 \u0995\u09b0\u09c7 \u09ad\u09be\u09b2 \u0995\u09b0\u09c7 \u09ae\u09c7\u09b6\u09be\u09a8\u0964 \u0995\u09bf\u099b\u09c1 \u0995\u09be\u099f\u09be \u09ac\u09b8\u09a8\u09cd\u09a4 \u09aa\u09c7\u0981\u09af\u09bc\u09be\u099c \u09a6\u09bf\u09af\u09bc\u09c7 \u09b8\u09be\u099c\u09bf\u09af\u09bc\u09c7 \u09a8\u09bf\u09a8\u0964 \u0986\u09aa\u09a8\u09bf \u098f\u0995\u09be \u098f\u099f\u09bf \u0996\u09c7\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8 \u09ac\u09be \u0995\u09bf\u099b\u09c1 \u09ad\u09be\u099c\u09be \u099a\u09be\u09b2 \u09a6\u09bf\u09af\u09bc\u09c7 \u098f\u099f\u09bf \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964 \u09a7\u09be\u09b0\u09a3\u09be\u099f\u09bf\u09b0 \u0995\u09cd\u09b7\u09c7\u09a4\u09cd\u09b0\u09c7 \u098f\u099f\u09bf \u098f\u09a4\u099f\u09be\u0987 \u0986\u09b8\u09b2 \u09a6\u09c7\u0996\u09be\u099a\u09cd\u099b\u09c7 \u09af\u09c7 \u0995\u09c7\u0989 \u09ac\u09bf\u09b6\u09cd\u09ac\u09be\u09b8 \u0995\u09b0\u09ac\u09c7 \u09a8\u09be \u09af\u09c7 \u098f\u09b0 \u0996\u09be\u09ac\u09be\u09b0\u0997\u09c1\u09b2\u09bf \u09ac\u09be\u0995\u09c0 \u0996\u09be\u09ac\u09be\u09b0 \u09a6\u09bf\u09af\u09bc\u09c7 \u09aa\u09cd\u09b0\u09b8\u09cd\u09a4\u09c1\u09a4\u0964\n<\/p>\n<h3>\n  8 \u09b0\u09c1\u099f\u09bf\u09b0 \u09aa\u09c1\u09a1\u09bf\u0982<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/10-dishes-prepared-with-leftover-food\/bread-pudding\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72837-6098c1fa0ff5a.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  \u09aa\u09be\u0989\u09b0\u09c1\u099f\u09bf \u09aa\u09c1\u09a1\u09bf\u0982.\n<\/p>\n<p>\n  \u09af\u09a6\u09bf \u0986\u09aa\u09a8\u09be\u09b0 \u099c\u09be\u09af\u09bc\u0997\u09be\u09af\u09bc \u09b0\u09c1\u099f\u09bf\u099f\u09bf \u09ac\u09be\u09b8\u09bf \u09b9\u09af\u09bc\u09c7 \u099a\u09b2\u09c7\u099b\u09c7 \u098f\u09ac\u0982 \u0986\u09aa\u09a8\u09bf \u098f\u099f\u09bf \u09b8\u09c7\u099f\u09bf\u09b0 \u09ae\u09a4\u09cb \u09ac\u09cd\u09af\u09ac\u09b9\u09be\u09b0 \u0995\u09b0\u09a4\u09c7 \u099a\u09be\u09a8 \u09a8\u09be \u09a4\u09ac\u09c7 \u0986\u09aa\u09a8\u09bf \u098f\u099f\u09bf \u09a5\u09c7\u0995\u09c7 \u098f\u0995\u099f\u09bf \u09b8\u09c1\u09b8\u09cd\u09ac\u09be\u09a6\u09c1 \u09ae\u09bf\u09b7\u09cd\u099f\u09bf \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964 \u09b0\u09c1\u099f\u09bf\u09b0 \u099b\u09cb\u099f \u099b\u09cb\u099f \u099f\u09c1\u0995\u09b0\u09cb \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09c7 \u098f\u09a4\u09c7 \u09a1\u09bf\u09ae, \u09a6\u09c1\u09a7, \u099a\u09bf\u09a8\u09bf, \u098f\u0995 \u099a\u09bf\u09ae\u099f\u09bf \u09b2\u09ac\u09a3, \u09a6\u09be\u09b0\u09c1\u099a\u09bf\u09a8\u09bf \u0997\u09c1\u0981\u09a1\u09bc\u09cb \u098f\u09ac\u0982 \u0995\u09bf\u099b\u09c1 \u09ad\u09cd\u09af\u09be\u09a8\u09bf\u09b2\u09be \u098f\u09b8\u09c7\u09a8\u09cd\u09b8 \u09ae\u09bf\u09b6\u09bf\u09af\u09bc\u09c7 \u09a8\u09bf\u09a8\u0964 \u0997\u09cd\u09b0\u09be\u0987\u09b8\u09a1 \u09ac\u09c7\u0995\u09bf\u0982 \u09a1\u09bf\u09b6\u09c7 \u09b8\u09be\u09ae\u0997\u09cd\u09b0\u09c0\u0997\u09c1\u09b2\u09bf .\u09be\u09b2\u09be\u0964 45 \u09ae\u09bf\u09a8\u09bf\u099f\u09c7\u09b0\u0993 \u09ac\u09c7\u09b6\u09bf \u09b8\u09ae\u09af\u09bc \u09a7\u09b0\u09c7 \u09ac\u09c7\u0995 \u0995\u09b0\u09c1\u09a8\u0964 \u0995\u09bf\u099b\u09c1 \u09b9\u09c1\u0987\u09aa\u09a1 \u0995\u09cd\u09b0\u09bf\u09ae \u09a6\u09bf\u09af\u09bc\u09c7 \u09aa\u09b0\u09bf\u09ac\u09c7\u09b6\u09a8 \u0995\u09b0\u09c1\u09a8\u0964 \u0986\u09aa\u09a8\u09bf \u09a5\u09be\u09b2\u09be\u099f\u09bf \u09ab\u09cd\u09b0\u09bf\u099c\u09c7 \u09b0\u09c7\u0996\u09c7 \u09a0\u09be\u09a8\u09cd\u09a1\u09be \u09ae\u09bf\u09b7\u09cd\u099f\u09bf \u09b9\u09bf\u09b8\u09be\u09ac\u09c7 \u0996\u09c7\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964\n<\/p>\n<h3>\n  9 \u0989\u09a6\u09cd\u09ad\u09bf\u099c\u09cd\u099c \u0995\u09be\u099f\u09b2\u09c7\u099f<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/10-dishes-prepared-with-leftover-food\/vegetable-cutlet\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72837-6098c1fb7fb42.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  \u09ad\u09c7\u099c\u09bf\u099f\u09c7\u09ac\u09b2 \u0995\u09be\u099f\u09b2\u09c7\u099f\u0964\n<\/p>\n<p>\n  \u09af\u09a6\u09bf \u0986\u09aa\u09a8\u09bf \u099b\u09cb\u09b2\u09be \u09ac\u09be \u09b0\u09be\u099c\u09ae\u09be\u09b8 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09c7\u09a8 \u098f\u09ac\u0982 \u09a4\u09be\u09a6\u09c7\u09b0 \u0995\u09c0 \u0995\u09b0\u09ac\u09c7\u09a8 \u09ad\u09c7\u09ac\u09c7 \u09ab\u09cd\u09b0\u09bf\u099c\u09c7 \u09a6\u09be\u0981\u09a1\u09bc\u09bf\u09af\u09bc\u09c7 \u09a5\u09be\u0995\u09c7\u09a8, \u09a4\u09ac\u09c7 \u0986\u09aa\u09a8\u09bf \u098f\u0987 \u09a5\u09be\u09b2\u09be\u099f\u09bf \u09aa\u09b0\u09c0\u0995\u09cd\u09b7\u09be \u0995\u09b0\u09c7 \u09a6\u09c7\u0996\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8 \u098f\u09ac\u0982 \u098f\u0995\u099f\u09bf \u09b8\u09cd\u09ac\u09be\u09b8\u09cd\u09a5\u09cd\u09af\u0995\u09b0 \u09a8\u09be\u09b8\u09cd\u09a4\u09be \u09aa\u09cd\u09b0\u09b8\u09cd\u09a4\u09c1\u09a4 \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964\n<\/p>\n<p>\n  \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u09b0\u09be\u099c\u09ae\u09be\u09b8 \u09ac\u09be \u099b\u09cb\u09b2\u09be \u09ae\u09be\u09b6 \u0995\u09b0\u09c1\u09a8\u0964 \u098f\u09a4\u09c7 \u0995\u09b0\u09cd\u09a8\u09ab\u09cd\u09b2\u09be\u09b0 \u09ac\u09be \u099b\u09cb\u09b2\u09be \u09ae\u09af\u09bc\u09a6\u09be \u09af\u09c1\u0995\u09cd\u09a4 \u0995\u09b0\u09c1\u09a8 \u09af\u09be \u098f\u0995\u099f\u09bf \u09ac\u09be\u0981\u09a7\u09be\u0987 \u098f\u099c\u09c7\u09a8\u09cd\u099f \u09b9\u09bf\u09b8\u09be\u09ac\u09c7 \u0995\u09be\u099c \u0995\u09b0\u09ac\u09c7\u0964 \u09ae\u09bf\u09b6\u09cd\u09b0\u09a3\u099f\u09bf \u09a6\u09bf\u09af\u09bc\u09c7 \u09b8\u09ae\u09a4\u09b2 \u0998\u09a8 \u0997\u09cb\u09b2\u09be\u0995\u09be\u09b0 \u09ac\u09b2\u0997\u09c1\u09b2\u09bf \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09c1\u09a8\u0964 \u0995\u09bf\u099b\u09c1\u099f\u09be \u09b0\u09c1\u099f\u09bf\u09b0 \u099f\u09c1\u0995\u09b0\u09cb \u099f\u09c1\u0995\u09b0\u09cb \u09a6\u09bf\u09af\u09bc\u09c7 \u098f\u099f\u09bf\u0995\u09c7 \u09b2\u09c7\u09aa\u09c1\u09a8 \u098f\u09ac\u0982 \u09ad\u09be\u099c\u09c1\u09a8\u0964 \u0995\u09be\u099f\u09be \u09aa\u09c7\u0981\u09af\u09bc\u09be\u099c, \u09b8\u09ac\u09c1\u099c \u09ae\u09b0\u09bf\u099a \u098f\u09ac\u0982 \u09a7\u09a8\u09bf\u09af\u09bc\u09be \u09aa\u09be\u09a4\u09be \u09a6\u09bf\u09af\u09bc\u09c7 \u098f\u099f\u09bf\u0995\u09c7 \u09b8\u09be\u099c\u09bf\u09af\u09bc\u09c7 \u09a8\u09bf\u09a8\u0964 \u0995\u09bf\u099b\u09c1 \u09a7\u09a8\u09c7 \u099a\u09be\u099f\u09a8\u09bf \u09ac\u09be \u099f\u09ae\u09c7\u099f\u09cb \u0995\u09c7\u099a\u09be\u09aa \u09a6\u09bf\u09af\u09bc\u09c7 \u09aa\u09b0\u09bf\u09ac\u09c7\u09b6\u09a8 \u0995\u09b0\u09c1\u09a8\u0964\n<\/p>\n<h3>\n  10 \u0995\u09b2\u09be \u09b9\u09be\u09b2\u0993\u09af\u09bc\u09be<br \/>\n<\/h3>\n<p>\n  <a href=\"https:\/\/www.wonderslist.com\/10-dishes-prepared-with-leftover-food\/banana-halwa\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/inform.click\/wp-content\/uploads\/2021\/05\/post-72837-6098c1fcda9bf.webp\" alt=\"\" \/><\/a>\n<\/p>\n<p>\n  \u0995\u09b2\u09be \u09b9\u09be\u09b2\u0993\u09af\u09bc\u09be\u0964\n<\/p>\n<p>\n  \u09aa\u09be\u0995\u09be \u0995\u09b2\u09be\u0997\u09c1\u09b2\u09bf \u09ac\u09be\u0995\u09c0 \u0996\u09be\u09ac\u09be\u09b0\u09c7\u09b0 \u09b8\u09be\u09a5\u09c7 \u09aa\u09cd\u09b0\u09b8\u09cd\u09a4\u09c1\u09a4 \u098f\u0987 \u09ae\u09a8\u09cb\u09b0\u09ae \u0996\u09be\u09ac\u09be\u09b0\u0997\u09c1\u09b2\u09bf \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09a4\u09c7 \u09ac\u09cd\u09af\u09ac\u09b9\u09be\u09b0 \u0995\u09b0\u09be \u09af\u09c7\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7 the \u0995\u09b2\u09be\u099f\u09bf \u099b\u09bf\u099f\u09bf\u09af\u09bc\u09c7 \u099f\u09c1\u0995\u09b0\u09cb \u0995\u09b0\u09c1\u09a8\u0964 \u0995\u09b2\u09be \u09aa\u09c1\u09b0\u09cb \u099b\u09a1\u09bc\u09bf\u09af\u09bc\u09c7 \u09a8\u09be \u09b9\u0993\u09af\u09bc\u09be \u09aa\u09b0\u09cd\u09af\u09a8\u09cd\u09a4 \u098f\u0997\u09c1\u09b2\u09bf \u098f\u0995\u099f\u09bf \u0995\u09a1\u09bc\u09be\u0987\u09a4\u09c7 \u0995\u09bf\u099b\u09c1\u099f\u09be \u0998\u09bf \u09a6\u09bf\u09af\u09bc\u09c7 \u09a8\u09c7\u09a1\u09bc\u09c7 \u09a8\u09bf\u09a8\u0964 \u098f\u09ac\u09be\u09b0 \u09b8\u09cd\u09ac\u09be\u09a6 \u0993 \u099c\u09b2 \u0985\u09a8\u09c1\u09af\u09be\u09af\u09bc\u09c0 \u099a\u09bf\u09a8\u09bf \u09a6\u09bf\u09a8\u0964 \u09ae\u09bf\u09b6\u09cd\u09b0\u09a3\u099f\u09bf \u0998\u09a8 \u09b9\u0993\u09af\u09bc\u09be \u09aa\u09b0\u09cd\u09af\u09a8\u09cd\u09a4 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u09b9\u09a4\u09c7 \u09a6\u09bf\u09a8\u0964 \u0995\u09be\u099f\u09be \u09b6\u09c1\u0995\u09a8\u09cb \u09ab\u09b2 \u098f\u09ac\u0982 \u0995\u09bf\u099b\u09c1 \u098f\u09b2\u09be\u099a \u0997\u09c1\u0981\u09a1\u09bc\u09cb \u09a6\u09bf\u09af\u09bc\u09c7 \u09b8\u09be\u099c\u09bf\u09af\u09bc\u09c7 \u09a8\u09bf\u09a8\u0964\n<\/p>\n<\/p>\n<div id=\"PostUnique_PostSource\" style=\"padding-top: 50px\">\n  \u09b0\u09c7\u0995\u09b0\u09cd\u09a1\u09bf\u0982 \u0989\u09a4\u09cd\u09b8: <a target=\"_blank\" rel=\"noopener nofollow\" href=\"https:\/\/www.wonderslist.com\/10-dishes-prepared-with-leftover-food\/\">wonderslist.com<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0985\u09ac\u09b6\u09bf\u09b7\u09cd\u099f \u0996\u09be\u09ac\u09be\u09b0 \u09a6\u09bf\u09af\u09bc\u09c7 \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09be \u0996\u09be\u09ac\u09be\u09b0\u0964 \u09b8\u09b9\u099c \u098f\u09ac\u0982 \u09a6\u09cd\u09b0\u09c1\u09a4 \u09a4\u09c8\u09b0\u09bf \u0995\u09b0\u09a4\u09c7, \u0986\u09aa\u09a8\u09bf \u09a6\u09bf\u09a8\u09c7\u09b0 \u09af\u09c7 \u0995\u09cb\u09a8\u0993 \u09b8\u09ae\u09af\u09bc \u098f\u0997\u09c1\u09b2\u09bf \u0989\u09aa\u09ad\u09cb\u0997 \u0995\u09b0\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964 \u0986\u09ae\u09b0\u09be \u098f\u09b0\u0995\u09ae \u09a6\u09b6\u099f\u09bf \u09a6\u09cd\u09b0\u09c1\u09a4 \u09a5\u09be\u09b2\u09be \u09b0\u09be\u09a8\u09cd\u09a8\u09be \u0995\u09b0\u09c7\u099b\u09bf\u09b2\u09be\u09ae<\/p>\n","protected":false},"author":1,"featured_media":87508,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1,558,727],"tags":[],"class_list":["post-245488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bez-kategorii","category-558","category-uncategorized-bn"],"_links":{"self":[{"href":"https:\/\/inform.click\/bn\/wp-json\/wp\/v2\/posts\/245488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inform.click\/bn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inform.click\/bn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inform.click\/bn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inform.click\/bn\/wp-json\/wp\/v2\/comments?post=245488"}],"version-history":[{"count":0,"href":"https:\/\/inform.click\/bn\/wp-json\/wp\/v2\/posts\/245488\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inform.click\/bn\/wp-json\/wp\/v2\/media\/87508"}],"wp:attachment":[{"href":"https:\/\/inform.click\/bn\/wp-json\/wp\/v2\/media?parent=245488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inform.click\/bn\/wp-json\/wp\/v2\/categories?post=245488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inform.click\/bn\/wp-json\/wp\/v2\/tags?post=245488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}